{"id":1,"count":4,"description":"","link":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/","name":"Non categorizzato","slug":"non-categorizzato","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Non categorizzato Archivi - Riccione Piadina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Non categorizzato Archivi - Riccione Piadina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/\" \/>\n<meta property=\"og:site_name\" content=\"Riccione Piadina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/c\\\/non-categorizzato\\\/\",\"url\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/c\\\/non-categorizzato\\\/\",\"name\":\"Non categorizzato Archivi - Riccione Piadina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/c\\\/non-categorizzato\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/c\\\/non-categorizzato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non categorizzato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/\",\"name\":\"Riccione Piadina\",\"description\":\"For over 30 years, Riccione Piadina has been bringing the traditional Romagnola piadina to the tables of Italians: Classic, Organic, Gluten-Free, Whole Wheat, and the authentic Rimini's IGP.\",\"publisher\":{\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#organization\"},\"alternateName\":\"Riccione Piadina\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#organization\",\"name\":\"Riccione S.r.l.\",\"url\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/riccionepiadina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Riccione-Piadina-produzione-piadine-romagnole-certificate.png\",\"contentUrl\":\"https:\\\/\\\/riccionepiadina.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Riccione-Piadina-produzione-piadine-romagnole-certificate.png\",\"width\":152,\"height\":118,\"caption\":\"Riccione S.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/riccionepiadina.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Riccione.Piadina\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RICCIONEPIADINA\",\"https:\\\/\\\/www.instagram.com\\\/riccionepiadina\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Non categorizzato Archivi - Riccione Piadina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/","og_locale":"en_US","og_type":"article","og_title":"Non categorizzato Archivi - Riccione Piadina","og_url":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/","og_site_name":"Riccione Piadina","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/","url":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/","name":"Non categorizzato Archivi - Riccione Piadina","isPartOf":{"@id":"https:\/\/riccionepiadina.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/riccionepiadina.com\/en\/c\/non-categorizzato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/riccionepiadina.com\/en\/"},{"@type":"ListItem","position":2,"name":"Non categorizzato"}]},{"@type":"WebSite","@id":"https:\/\/riccionepiadina.com\/en\/#website","url":"https:\/\/riccionepiadina.com\/en\/","name":"Riccione Piadina","description":"For over 30 years, Riccione Piadina has been bringing the traditional Romagnola piadina to the tables of Italians: Classic, Organic, Gluten-Free, Whole Wheat, and the authentic Rimini's IGP.","publisher":{"@id":"https:\/\/riccionepiadina.com\/en\/#organization"},"alternateName":"Riccione Piadina","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/riccionepiadina.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/riccionepiadina.com\/en\/#organization","name":"Riccione S.r.l.","url":"https:\/\/riccionepiadina.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/riccionepiadina.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/riccionepiadina.com\/wp-content\/uploads\/2023\/05\/Riccione-Piadina-produzione-piadine-romagnole-certificate.png","contentUrl":"https:\/\/riccionepiadina.com\/wp-content\/uploads\/2023\/05\/Riccione-Piadina-produzione-piadine-romagnole-certificate.png","width":152,"height":118,"caption":"Riccione S.r.l."},"image":{"@id":"https:\/\/riccionepiadina.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Riccione.Piadina","https:\/\/www.youtube.com\/user\/RICCIONEPIADINA","https:\/\/www.instagram.com\/riccionepiadina\/"]}]}},"_links":{"self":[{"href":"https:\/\/riccionepiadina.com\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riccionepiadina.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/riccionepiadina.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/riccionepiadina.com\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}